{"id":4299,"date":"2024-11-22T18:37:17","date_gmt":"2024-11-22T17:37:17","guid":{"rendered":"https:\/\/paroisses-nancy-sud.fr\/HOME\/?p=4299"},"modified":"2024-11-22T18:37:17","modified_gmt":"2024-11-22T17:37:17","slug":"solennite-du-christ-roi-de-lunivers","status":"publish","type":"post","link":"https:\/\/paroisses-nancy-sud.fr\/HOME\/solennite-du-christ-roi-de-lunivers\/","title":{"rendered":"<strong>Solennit\u00e9 du Christ Roi de l\u2019univers<\/strong>"},"content":{"rendered":"\n<p><span style=\"color: #000000;\"><strong>Solennit\u00e9 du Christ Roi de l\u2019univers<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\">Nous voici parvenus au dernier dimanche de l\u2019ann\u00e9e liturgique, o\u00f9 nous f\u00eatons la solennit\u00e9 du Christ Roi. Dimanche prochain premier dimanche de l\u2019Avent, s\u2019ouvrira une nouvelle ann\u00e9e. <strong>La f\u00eate du Christ Roi<\/strong> est un ajout r\u00e9cent. Elle a \u00e9t\u00e9 institu\u00e9e en 1925 par le pape Pie XI dans le but d\u2019affirmer la royaut\u00e9 du Christ sur tout l\u2019univers.<\/span><\/p>\n<p><span style=\"color: #000000;\">En fait, ce titre de roi n\u2019est gu\u00e8re donn\u00e9 au Christ que dans les r\u00e9cits de la Passion et surtout par d\u00e9rision, un signe, peut-\u00eatre pour nous sugg\u00e9rer que cette royaut\u00e9 du Christ ne peut \u00eatre que tr\u00e8s diff\u00e9rente de celles des puissants de notre terre. J\u00e9sus nous dit lui-m\u00eame que\u00a0\u00ab\u00a0<em>sa royaut\u00e9 n\u2019est pas de ce monde<\/em>\u00a0\u00bb (Jean 18,36).\u00a0<\/span><\/p>\n<p><span style=\"color: #000000;\">Or cette diff\u00e9rence lui permet de nous dire quelle est la v\u00e9rit\u00e9 de Dieu. Et quelle est-elle sinon de nous r\u00e9v\u00e9ler que Dieu s\u2019int\u00e9resse tellement \u00e0 son peuple qu\u2019il le prend en charge et veille sur lui comme un p\u00e8re et une m\u00e8re s\u2019occupent de leurs enfants\u00a0? Cela depuis toujours, depuis les origines, malgr\u00e9 les infid\u00e9lit\u00e9s de la part des humains. La preuve nous en est donn\u00e9e\u00a0: l\u2019envoi de son propre Fils, qui nous dit que la raison de sa venue ici-bas est de rendre t\u00e9moignage \u00e0 la v\u00e9rit\u00e9. Lui aussi sera fid\u00e8le, jusqu\u2019\u00e0 devoir compara\u00eetre devant Pilate.<\/span><\/p>\n<p><span style=\"color: #000000;\">Et, m\u00eame dans ce contexte, la victoire finale reste objet d\u2019esp\u00e9rance, car \u00ab\u00a0<em>le Christ est l\u2019Alpha et l\u2019Om\u00e9ga, le Souverain de l\u2019univers<\/em>\u00a0\u00bb (Apocalypse de saint Jean 1, 8) et \u00ab\u00a0<em>la\u00a0royaut\u00e9 de Dieu ne sera pas d\u00e9truite<\/em>\u00a0\u00bb (proph\u00e8te Daniel 7,14). La vision de l\u2019Apocalypse reprend les termes de Daniel mais en pr\u00e9cisant les traits du \u00ab\u00a0Fils d\u2019homme\u00a0\u00bb\u00a0: agneau transperc\u00e9, mais vainqueur, le premier (alpha) et le dernier qui tient en sa main l\u2019histoire de l\u2019univers. Oui, que ton r\u00e8gne vienne.<\/span><\/p>\n<p><span style=\"color: #000000;\">Comme roi, J\u00e9sus nous guide, nous montre le chemin, un chemin qu\u2019il emprunte d\u2019abord lui-m\u00eame. Pauvre avec les pauvres, joyeux avec ceux qui sont dans la joie, esp\u00e9rant avec ceux qui souffrent, le Christ nous trace un chemin de paix et d\u2019humilit\u00e9. Acclamons-le\u00a0!<\/span><\/p>\n<p style=\"text-align: right;\"><span style=\"color: #000000;\"><em>\u00a0D\u2019apr\u00e8s la revue Prions en \u00c9glise<\/em><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Solennit\u00e9 du Christ Roi de l\u2019univers Nous voici parvenus au dernier dimanche de l\u2019ann\u00e9e liturgique, o\u00f9 nous f\u00eatons la solennit\u00e9 du Christ Roi. Dimanche prochain premier dimanche de l\u2019Avent, s\u2019ouvrira une nouvelle ann\u00e9e. La f\u00eate du Christ Roi est un ajout r\u00e9cent. Elle a \u00e9t\u00e9 institu\u00e9e en 1925 par le pape Pie XI dans le&hellip; <br \/> <a class=\"read-more\" href=\"https:\/\/paroisses-nancy-sud.fr\/HOME\/solennite-du-christ-roi-de-lunivers\/\">Lire la suite<\/a><\/p>\n","protected":false},"author":5,"featured_media":523,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/posts\/4299"}],"collection":[{"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/comments?post=4299"}],"version-history":[{"count":1,"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/posts\/4299\/revisions"}],"predecessor-version":[{"id":4300,"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/posts\/4299\/revisions\/4300"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/media\/523"}],"wp:attachment":[{"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/media?parent=4299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/categories?post=4299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/tags?post=4299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}