{"id":4331,"date":"2024-12-08T17:26:10","date_gmt":"2024-12-08T16:26:10","guid":{"rendered":"https:\/\/paroisses-nancy-sud.fr\/HOME\/?p=4331"},"modified":"2024-12-08T17:26:10","modified_gmt":"2024-12-08T16:26:10","slug":"annonces-de-sainte-jeanne-de-chantal-et-saint-francois-de-sales-du-8-decembre","status":"publish","type":"post","link":"https:\/\/paroisses-nancy-sud.fr\/HOME\/annonces-de-sainte-jeanne-de-chantal-et-saint-francois-de-sales-du-8-decembre\/","title":{"rendered":"Annonces de Sainte-Jeanne-de-Chantal et Saint-Fran\u00e7ois-de-Sales du 8 d\u00e9cembre"},"content":{"rendered":"\n<p><span style=\"color: #000000;\"><span style=\"text-decoration: underline;\"><strong>Bapt\u00eame<br \/><\/strong><\/span><strong>Dimanche 8 d\u00e9cembre \u00e0 Jarville, pendant la messe, bapt\u00eame <\/strong>de Iris. Nous portons ce b\u00e9b\u00e9 et sa famille dans notre pri\u00e8re.<\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"text-decoration: underline;\"><strong>Table ouverte du 2<sup>\u00e8me<\/sup> dimanche du mois<br \/><\/strong><\/span><strong>Ce dimanche 8 d\u00e9cembre table ouverte \u00e0 Jarville. <\/strong>N\u2019oublions pas d\u2019inviter les personnes isol\u00e9es, seules. Nous partagerons le repas avec les membres du groupe <em>\u2018\u2019Foi et lumi\u00e8re\u00a0\u2018\u2019<\/em>.<\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"text-decoration: underline;\"><strong>Lundi 9 d\u00e9cembre, solennit\u00e9 de l\u2019Immacul\u00e9e Conception<br \/><\/strong><\/span><strong>La messe sera c\u00e9l\u00e9br\u00e9e \u00e0 18h30 \u00e0 Jarville<\/strong>. Elle sera pr\u00e9c\u00e9d\u00e9e de la pri\u00e8re du Rosaire \u00e0\u00a017h \u00e0 Fl\u00e9ville et \u00e0 17h30 \u00e0 Jarville.<\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"text-decoration: underline;\"><strong>Temps de l\u2019Avent : Se pr\u00e9parer \u00e0 No\u00ebl<br \/><\/strong><\/span><strong>\u00a0&#8211; C<\/strong><strong>ollecte au fond des \u00e9glises<br \/><\/strong>Tout le temps de l\u2019Avent, un panier plac\u00e9 au fond de l\u2019\u00e9glise recueillera vos dons, produits d\u2019hygi\u00e8ne, de pu\u00e9riculture (savon, gel douche, shampoing, couches pour b\u00e9b\u00e9s), produits alimentaires non p\u00e9rissables (huile, farine, th\u00e9, caf\u00e9, chocolat en tablettes ou en poudre, biscuits), lait, jus de fruits et des surprises ou friandises de No\u00ebl\u00a0pour les personnes en difficult\u00e9, redistribu\u00e9s par les services de notre secteur. Un grand merci !<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>\u00a0&#8211; March\u00e9s de No\u00ebl<br \/><\/strong><strong>Le samedi 7 d\u00e9cembre \u00e0 Laneuveville\u00a0(17h \u00e0 19h) et le dimanche 8 d\u00e9cembre \u00e0 Jarville (10h \u00e0 13h)\u00a0: <\/strong>Vous pourrez y trouver : hu\u00eetres, escargots, charcuteries lorraines, rissoles, fruits et l\u00e9gumes ainsi que les d\u00e9cos confectionn\u00e9es par \u00ab\u00a0<em>les abeilles du mercredi\u00a0<\/em>\u00bb.<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>\u00a0&#8211; Parvis de No\u00ebl<br \/><\/strong><strong>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0Le Jeudi 19 d\u00e9cembre, sur<\/strong> <strong>le parvis et dans l\u2019\u00e9glise de Jarville <\/strong>de 15h30 \u00e0 17h30\u00a0<strong>c<\/strong>omme chaque ann\u00e9e, des moments d\u2019accueil \u2018\u2019Sp\u00e9cial Avent\u2019\u2019 : marrons, chocolat et vin chauds, g\u00e2teaux, musique, orgue de Barbarie, visite de la cr\u00e8che.<br \/><strong>\u00a0 \u00a0 \u00a0 \u00a0 A Flavigny, le vendredi 20 d\u00e9cembre \u00e0 16h \u00e0 l\u2019\u00e9glise et sur le parvis : <\/strong>chants de No\u00ebl, chemin de lumi\u00e8re vers la cr\u00e8che, vin et chocolat chauds, marrons chauds en partenariat avec le groupe \u2018\u2019Vivre ensemble\u2019\u2019<\/span><\/p>\n<p><span style=\"color: #000000;\">\u00a0&#8211; <strong>Op\u00e9ration \u2018\u2019Oranges\u2019\u2019 de S\u0153ur Emmanuelle et de S\u0153ur Sara !<br \/><\/strong>Dimanche 8 d\u00e9cembre \u00e0 Flavigny, puis les 14-15 d\u00e9cembre \u00e0 Heillecourt, Jarville, Laneuveville, Ludres puis le 22 d\u00e9cembre \u00e0 Neuves-Maisons et \u00e0 Fl\u00e9ville\u00a0: 1 orange = 1 euro.<\/span><br \/><span style=\"color: #000000;\">Des oranges, pour rappeler la distribution d&rsquo;oranges op\u00e9r\u00e9e par s\u0153ur Emmanuelle aux enfants des rues du Soudan du sud\u00a0(mais aussi \u00e9largissement des aides au Liban et \u00e0 l\u2019Egypte), aide nutritionnelle, priorit\u00e9 \u00e0 l&rsquo;\u00e9ducation et plus particuli\u00e8rement des filles.<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>\u00a0&#8211; Eglises ouvertes et visite des cr\u00e8ches : <br \/><\/strong><strong>A Jarville, l\u2019\u00e9glise est ouverte tous les jours. A Heillecourt, le jeudi et vendredi de 16h \u00e0 17h.<br \/><\/strong><strong>A Fl\u00e9ville<\/strong> l\u2019\u00e9glise sera ouverte <strong>samedi 21 d\u00e9cembre entre 15h et 18h.<br \/><\/strong><strong>A Ludres<\/strong> les mercredis et samedis matin de 10h \u00e0 midi, visite de la cr\u00e8che.<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>\u00a0&#8211; Concerts de No\u00ebl<br \/><\/strong><strong>Samedi 21 d\u00e9cembre \u00e0 20h Jarville, <\/strong>avec <em>La Cantalud<strong>, <\/strong>la Voix d\u2019Aulnes, Chorales de l\u2019\u00e9cole de musique de Varang\u00e9ville.<\/em><\/span><\/p>\n<p><span style=\"color: #000000;\"><strong><span style=\"text-decoration: underline;\">\u00a0Temps de pri\u00e8re mensuel \u00e0 Fl\u00e9ville \u2018\u2019Priez en Eglise\u2019\u2019<\/span><br \/><\/strong><strong>Ce mardi 10 d\u00e9cembre, \u00e0 15h, \u00e0 l\u2019\u00e9glise de Fl\u00e9ville, temps de pri\u00e8re <\/strong>d\u2019apr\u00e8s le livret \u2018\u2019Venez et priez\u2019\u2019.<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>\u00a0<span style=\"text-decoration: underline;\">Rencontre des \u00e9quipes du MCR (Mouvement Chr\u00e9tien des Retrait\u00e9s)<\/span><br \/><\/strong><strong>Le jeudi 12 d\u00e9cembre \u00e0 Heillecourt, 14h30 <\/strong>\u00e0 la salle Arc en Ciel<strong> et le mardi 17 d\u00e9cembre 14h30 \u00e0 Jarville, salles paroissiales, <\/strong>les \u00e9quipes du MCR se retrouvent pour leur r\u00e9union mensuelle.<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>\u00a0<span style=\"text-decoration: underline;\">Pri\u00e8re du soir du 2<sup>\u00e8me<\/sup> vendredi du mois :<\/span><br \/><\/strong><strong>Le vendredi 13 d\u00e9cembre, de 20h30 \u00e0 Jarville, <\/strong>pri\u00e8re du soir (chants, m\u00e9ditation, complies)<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong><span style=\"text-decoration: underline;\">\u00a0Eveil \u00e0 la foi<\/span><br \/><\/strong><strong>Le dimanche 15 d\u00e9cembre, \u00e0 10h \u00e0 Ludres, <\/strong>2<sup>\u00e8me<\/sup> rencontre des enfants et des parents de l\u2019Eveil \u00e0 la foi.<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong><span style=\"text-decoration: underline;\">\u00a0Vente au profit du Secours Catholique-Caritas France :<\/span><br \/><\/strong>Une vente de divers objets sera propos\u00e9e \u00e0 partir du week-end <strong>du 7 d\u00e9cembre \u00e0 Heillecourt<\/strong> et du <strong>14-15 d\u00e9cembre \u00e0 Laneuveville et Jarville<\/strong>(bougies, cr\u00e8ches, d\u00e9corations sapins, jus de pommes) au b\u00e9n\u00e9fice du Secours Catholique. Merci de votre g\u00e9n\u00e9rosit\u00e9.<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong><span style=\"text-decoration: underline;\">\u00a0Parcours Alpha<\/span><br \/><\/strong><strong>Le mardi 7 janvier 2025 \u00e0 Jarville de 19h30 \u00e0 22h<\/strong> dans les salles \u00e0 droite de l\u2019\u00e9glise, <strong>vous \u00eates invit\u00e9s \u00e0 une rencontre sur le th\u00e8me\u00a0: \u2018Quel est le sens de la vie\u00a0?\u2019\u2019. <\/strong>La rencontre d\u00e9bute par un moment convivial autour d\u2019un repas, suivi d\u2019un bref expos\u00e9 puis d\u2019un temps d\u2019\u00e9change. <strong>Ce parcours est ouvert \u00e0 tous.<\/strong> Chacun est accueilli de mani\u00e8re d\u00e9contract\u00e9e pour \u00e9changer en petits groupes, <strong>d\u00e9couvrir ou red\u00e9couvrir la foi chr\u00e9tienne<\/strong>. Ensuite plusieurs rencontres sont pr\u00e9vues. Contact\u00a0: Odile Bonmati 06 23 46 74 17.\u00a0<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>\u00a0<span style=\"text-decoration: underline;\">Repas paroissial annuel<\/span><br \/><\/strong><strong style=\"font-size: revert;\">Le dimanche 19 janvier, nos deux paroisses se retrouvent pour le repas annuel, \u00e0 la Maison du Temps Libre \u00e0 Heillecourt. <\/strong><span style=\"font-size: revert;\">Voir les tracts au fond des \u00e9glises, on peut s\u2019inscrire d\u00e8s maintenant !<\/span><\/span><\/p>\n<p><span style=\"color: #000000;\"><strong><span style=\"text-decoration: underline;\">\u00a0Galette des Rois des b\u00e9n\u00e9voles de Saint-Fran\u00e7ois-de-Sales :<\/span><br \/><\/strong><strong>Le dimanche 26 janvier, \u00e0 Jarville, \u00e0 16h, <\/strong>les b\u00e9n\u00e9voles de la paroisse de Saint-Fran\u00e7ois-de-Sales sont invit\u00e9s \u00e0 partager la galette des Rois.<\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"text-decoration: underline;\"><strong>Rencontre des jeunes AJC<br \/><\/strong><\/span>Nous vous proposons un week-end au monast\u00e8re d\u2019Orbey, <strong>samedi 25 et dimanche 26 janvier 2025<\/strong>, sur le th\u00e8me \u00ab\u00a0<em>Nous avons l\u2019esp\u00e9rance de la vie \u00e9ternelle, promise depuis toujours par Dieu qui ne ment pas\u00a0<\/em>\u00bb (lettre de saint Paul \u00e0 Tite 1,2). Retenez d\u00e9j\u00e0 la date\u00a0!<\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"text-decoration: underline;\"><strong>Assembl\u00e9e g\u00e9n\u00e9rale de <em>l\u2019Association Kermesse<br \/><\/em><\/strong><\/span>L\u2019assembl\u00e9e g\u00e9n\u00e9rale de l\u2019association Kermesse de Jarville aura lieu le <strong>samedi 21 d\u00e9cembre \u00e0 10h30<\/strong>, dans les salles paroissiales de Jarville.<\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"text-decoration: underline;\"><strong>Horaires des messes dominicales des 14 et 15 d\u00e9cembre 2024<br \/><\/strong><\/span><strong>Samedi 14 d\u00e9cembre\u00a0: 18h <\/strong>Heillecourt, Laneuveville, Messein<br \/><strong>Dimanche 15 d\u00e9cembre : 10 h30 <\/strong>Jarville, Bainville sur Madon <strong>11h<\/strong> Ludres<\/span><\/p>\n<p>\u00a0<\/p>\n<p><span style=\"color: #000000;\"><span style=\"text-decoration: underline;\"><strong>Cartes de voeux<br \/><\/strong><\/span><strong>Le 29 d\u00e9cembre prochain s&rsquo;ouvrira le jubil\u00e9 de l&rsquo;esp\u00e9rance.<\/strong> A cette occasion le service des jeunes organise un p\u00e8lerinage du 25 juillet au 6 aout \u00e0 destination des jeunes (18-35 ans). Nous vous avions d\u00e9j\u00e0 sollicit\u00e9s pour nous aider financi\u00e8rement lors des JMJ de Lisbonne en 2023 et vous aviez r\u00e9pondu pr\u00e9sent et nous vous en remercions car gr\u00e2ce \u00e0 vous nous avons pu vivre un moment inoubliable. Pour le Jubil\u00e9 2025, nous vous sollicitons encore. C&rsquo;est pourquoi en cette fin d&rsquo;ann\u00e9e nous vous proposons <strong>une vente de cartes de v\u0153ux.<\/strong> L&rsquo;argent r\u00e9colt\u00e9 ira au service des jeunes pour diminuer le prix du voyage.\u00a0 Merci \u00e0 vous pour votre aide et bon temps de l&rsquo;avent.<\/span><\/p>\n<p><span style=\"color: #000000;\"><span style=\"text-decoration: underline;\"><strong>Horaires des messes de No\u00ebl<br \/><\/strong><\/span><strong>Mardi 24 d\u00e9cembre : 18h Pulligny, Neuves-Maisons, Heillecourt (salle du Cosec),<br \/><\/strong><strong>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 21h Fl\u00e9ville, 22h15 Laneuveville<br \/><\/strong><strong>Mercredi 25 d\u00e9cembre\u00a0: 10h Xeuilley, 10h30 Jarville et Ludres<\/strong><\/span><\/p>\n<p><span style=\"text-decoration: underline; color: #000000;\"><strong>\u00a0<\/strong><strong>A<\/strong><strong>utres<\/strong><strong> Annonces<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Jubil\u00e9 2025\u00a0: Rendez-vous le 29 d\u00e9cembre pour l\u2019ouverture !<br \/><\/strong>Le Pape Fran\u00e7ois a souhait\u00e9 que l\u2019ann\u00e9e 2025 soit une\u00a0<a style=\"color: #000000;\" href=\"https:\/\/www.iubilaeum2025.va\/fr.html\">ann\u00e9e jubilaire<\/a>\u00a0pour notre \u00c9glise, sur le th\u00e8me : <em>\u00ab\u00a0P\u00e8lerins d\u2019Esp\u00e9rance<\/em>\u00a0\u00bb. Dans notre dioc\u00e8se, notre \u00e9v\u00eaque, <strong>Monseigneur Pierre-Yves Michel, vous invite \u00e0 entrer tous ensemble dans ce Jubil\u00e9 le dimanche 29 d\u00e9cembre 2024, \u00e0 la cath\u00e9drale de Nancy. \u00a0<\/strong>Rendez-vous \u00e0 <strong>10h45<\/strong>\u00a0devant l\u2019\u00e9glise Saint-S\u00e9bastien de Nancy pour marcher ensemble en procession vers la cath\u00e9drale, <strong>11h15<\/strong>\u00a0: messe dans la cath\u00e9drale Notre-Dame-de-l\u2019Annonciation de Nancy et temps convivial \u00e0 la sortie de la messe.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bapt\u00eameDimanche 8 d\u00e9cembre \u00e0 Jarville, pendant la messe, bapt\u00eame de Iris. Nous portons ce b\u00e9b\u00e9 et sa famille dans notre pri\u00e8re. Table ouverte du 2\u00e8me dimanche du moisCe dimanche 8 d\u00e9cembre table ouverte \u00e0 Jarville. N\u2019oublions pas d\u2019inviter les personnes isol\u00e9es, seules. Nous partagerons le repas avec les membres du groupe \u2018\u2019Foi et lumi\u00e8re\u00a0\u2018\u2019. Lundi&hellip; <br \/> <a class=\"read-more\" href=\"https:\/\/paroisses-nancy-sud.fr\/HOME\/annonces-de-sainte-jeanne-de-chantal-et-saint-francois-de-sales-du-8-decembre\/\">Lire la suite<\/a><\/p>\n","protected":false},"author":5,"featured_media":553,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/posts\/4331"}],"collection":[{"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/comments?post=4331"}],"version-history":[{"count":1,"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/posts\/4331\/revisions"}],"predecessor-version":[{"id":4332,"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/posts\/4331\/revisions\/4332"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/media\/553"}],"wp:attachment":[{"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/media?parent=4331"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/categories?post=4331"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/tags?post=4331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}