{"id":4359,"date":"2024-12-22T10:00:00","date_gmt":"2024-12-22T09:00:00","guid":{"rendered":"https:\/\/paroisses-nancy-sud.fr\/HOME\/?p=4359"},"modified":"2024-12-20T11:54:54","modified_gmt":"2024-12-20T10:54:54","slug":"maternite-de-marie-maternite-de-leglise","status":"publish","type":"post","link":"https:\/\/paroisses-nancy-sud.fr\/HOME\/maternite-de-marie-maternite-de-leglise\/","title":{"rendered":"<strong>Maternit\u00e9 de Marie, maternit\u00e9 de l&rsquo;\u00c9glise<\/strong>"},"content":{"rendered":"\n<p><span style=\"color: #000000;\"><strong>Maternit\u00e9 de Marie, maternit\u00e9 de l&rsquo;\u00c9glise<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\">Un jour que J\u00e9sus \u00e9tait en train d&rsquo;enseigner et que sa m\u00e8re et ses fr\u00e8res cherchaient en vain \u00e0 le rejoindre, il dit\u00a0: \u00ab\u00a0Ma m\u00e8re et mes fr\u00e8res sont ceux qui \u00e9coutent la parole de Dieu et la mettent en pratique.\u00a0\u00bb Ainsi est ouverte \u00e0 toute personne la possibilit\u00e9 d&rsquo;\u00eatre, en quelque sorte, m\u00e8re, fr\u00e8re, s\u0153ur du Christ, pourvu qu&rsquo;elle \u00e9coute la parole de Dieu et la mette en pratique.<\/span><\/p>\n<p><span style=\"color: #000000;\">Un fid\u00e8le-du-Christ, qu&rsquo;il soit la\u00efc, clerc ou consacr\u00e9, est un homme ou une femme attach\u00e9 au Christ par le lien de la foi et qui, par cons\u00e9quent, \u00e9coute la parole de Dieu et la met en pratique. Chaque fois que nous lisons et m\u00e9ditons l&rsquo;\u00c9criture Sainte, seuls ou en fraternit\u00e9s, chaque fois que nous transmettons la foi, la morale, la pri\u00e8re, tout ce qui fait l&rsquo;art de vivre du disciple de J\u00e9sus, \u00e0 nos enfants ou petits-enfants, chaque fois que nous mettons en \u0153uvre l&rsquo;\u00c9vangile dans nos choix concrets de vie, nous participons \u00e0 engendrer le Christ en nous et dans les autres. En un sens, si nous croyons aux paroles de J\u00e9sus, nous sommes \u00ab\u00a0m\u00e8res du Christ\u00a0\u00bb.<\/span><\/p>\n<p><span style=\"color: #000000;\">Attention cependant\u00a0: on n&rsquo;est pas chr\u00e9tien tout seul dans son coin. Si l&rsquo;on peut \u00eatre un chr\u00e9tien, un fid\u00e8le-du-Christ, c&rsquo;est uniquement en ayant part \u00e0 la foi de l&rsquo;\u00c9glise. Bien s\u00fbr, l&rsquo;\u00c9glise, c&rsquo;est la communaut\u00e9 chr\u00e9tienne dans son ensemble, gard\u00e9e en communion sur toute la terre par le pape et les \u00e9v\u00eaques, gard\u00e9e aussi en communion avec les ap\u00f4tres et les chr\u00e9tiens de toutes les \u00e9poques.<\/span><\/p>\n<p><span style=\"color: #000000;\">La Bible telle quelle n&rsquo;est pas la parole de Dieu. Hors de l&rsquo;\u00c9glise, la Bible n&rsquo;est qu&rsquo;un texte ancien, parfois inspirant, souvent indigeste. Proclam\u00e9e, c\u00e9l\u00e9br\u00e9e, m\u00e9dit\u00e9e, interpr\u00e9t\u00e9e par l&rsquo;\u00c9glise et dans l&rsquo;\u00c9glise, elle devient parole de Dieu capable de rejoindre toute personne, parole de Dieu concr\u00e8te et personnelle au point de devenir sacrement\u00a0: \u00ab\u00a0Je te baptise&#8230; Sois marqu\u00e9 de l&rsquo;Esprit Saint&#8230; Mon corps livr\u00e9 pour vous&#8230; Je te pardonne&#8230;\u00a0\u00bb<\/span><\/p>\n<p><span style=\"color: #000000;\">L&rsquo;\u00c9glise est m\u00e8re. Elle est m\u00e8re en \u00e9coutant la parole de Dieu et en la mettant en pratique. Elle est m\u00e8re en incarnant cette parole de Dieu dans sa mani\u00e8re de c\u00e9l\u00e9brer \u2013 sa liturgie \u2013 et dans sa mani\u00e8re d&rsquo;agir \u2013 dans son enseignement moral. De toutes ces mani\u00e8res, l&rsquo;\u00c9glise est m\u00e8re\u00a0: elle engendre le Christ dans les \u00e2mes et dans les corps. Ce qui est vrai en particulier de tout fid\u00e8le-du-Christ est vrai en g\u00e9n\u00e9ral de l&rsquo;\u00c9glise prise dans sa totalit\u00e9.<\/span><\/p>\n<p><span style=\"color: #000000;\">Si l&rsquo;\u00c9glise dans sa globalit\u00e9, et en particulier chaque fid\u00e8le-du-Christ qui a part \u00e0 la foi de l&rsquo;\u00c9glise, est m\u00e8re du Christ, c&rsquo;est bien s\u00fbr parce que l&rsquo;Esprit Saint, l&rsquo;Esprit de Dieu, est \u00e0 l&rsquo;\u0153uvre en elle. C&rsquo;est uniquement sous le souffle de l&rsquo;Esprit Saint que la parole de Dieu est devenue Ecriture Sainte, que l&rsquo;\u00c9criture Sainte devient chaque jour parole de Dieu et sacrements, que le Christ est cru aujourd&rsquo;hui, c\u00e9l\u00e9br\u00e9 aujourd&rsquo;hui, imit\u00e9 aujourd&rsquo;hui, pri\u00e9 aujourd&rsquo;hui.<\/span><\/p>\n<p><span style=\"color: #000000;\">La maternit\u00e9 de l&rsquo;\u00c9glise sous le souffle de l&rsquo;Esprit Saint est la condition de la maternit\u00e9 de chaque fid\u00e8le-du-Christ, chacun dans sa vocation, sous le souffle de l&rsquo;Esprit Saint. C&rsquo;est le m\u00eame Esprit Saint qui a souffl\u00e9 autrefois sur la Vierge Marie pour que la Parole de Dieu prenne chair en son sein, le m\u00eame Esprit Saint qui a souffl\u00e9 sur Elisabeth afin qu&rsquo;elle reconnaisse Celui qui \u00e9tait venu la visiter\u00a0: \u00ab\u00a0Tu es b\u00e9nie entre toutes les femmes, et le fruit de tes entrailles est b\u00e9ni. D\u2019o\u00f9 m\u2019est-il donn\u00e9 que la m\u00e8re de mon Seigneur vienne jusqu\u2019\u00e0 moi\u00a0?\u00a0\u00bb<\/span><\/p>\n<p><span style=\"color: #000000;\">Dans la maternit\u00e9 de Marie, toute maternit\u00e9 dans l&rsquo;\u00c9glise trouve son mod\u00e8le le plus accompli. Pour elle comme pour nous, il s&rsquo;agit d&rsquo;accueillir quelque chose qui nous d\u00e9passe, quelque chose qui ne proc\u00e8de pas uniquement de nous et qui pourtant ne peut pas advenir sans nous. Ce myst\u00e8re s&rsquo;\u00e9claire par celui de la maternit\u00e9 humaine\u00a0: la vie qui grandit dans le sein de la future m\u00e8re ne proc\u00e8de pas uniquement d&rsquo;elle, et pourtant elle prend une part active \u00e0 la mise au monde de ce nouvel \u00eatre. La vie du Christ qui grandit en Marie, en l&rsquo;\u00c9glise, en chacun de nous, est un pur don de l&rsquo;Esprit Saint, et pourtant nous y prenons part.<\/span><\/p>\n<p><span style=\"color: #000000;\">Apprenons de Marie comment croire \u00ab\u00a0\u00e0 l\u2019accomplissement des paroles qui lui furent dites de la part du Seigneur\u00a0\u00bb, comment c\u00e9l\u00e9brer, vivre et prier. Pour cela pas de meilleur moyen que la m\u00e9ditation de la vie du Christ \u00e0 l&rsquo;\u00e9cole de la Vierge Marie au moyen de la pri\u00e8re du rosaire. Les apparitions mariales, les enseignements des papes, le t\u00e9moignage des saints et de nos anc\u00eatres dans la foi nous y encouragent fortement.<\/span><\/p>\n<p><span style=\"color: #000000;\">En priant le rosaire, nous faisons m\u00e9moire de ce que Dieu a accompli dans la naissance et la pr\u00e9dication, la mort et la r\u00e9surrection du Seigneur J\u00e9sus.<\/span><\/p>\n<p><span style=\"color: #000000;\">Nous apprenons de Marie \u00e0 mieux conna\u00eetre le Seigneur J\u00e9sus authentique, toujours plus grand que l&rsquo;id\u00e9e que le monde nous en donne, celui qu&rsquo;elle a port\u00e9, mis au monde et accompagn\u00e9 jusqu&rsquo;\u00e0 la croix.<\/span><\/p>\n<p><span style=\"color: #000000;\">Nous laissons Marie engendrer en nous son Fils, nous former \u00e0 la ressemblance du Seigneur J\u00e9sus, faire de nous des fils et des filles de Dieu.<\/span><\/p>\n<p><span style=\"color: #000000;\">Nous accomplissons notre devoir de prier et d&rsquo;interc\u00e9der pour le monde entier, s\u00fbrs que nos demandes sont port\u00e9es par les mains de Marie.<\/span><\/p>\n<p><span style=\"color: #000000;\">Enfin, prier ensemble le rosaire, comme beaucoup le font en mai et en octobre, ou bien dans la rue, dans le bus, a aussi une valeur \u00e9vang\u00e9lisatrice.<\/span><\/p>\n<p><span style=\"color: #000000;\">Le rosaire est une pri\u00e8re autour de laquelle peuvent se retrouver jeunes et anciens, petits et grands, simples et savants, actifs et contemplatifs. Et si nous red\u00e9couvrions et faisions d\u00e9couvrir ce tr\u00e9sor au plus grand nombre dans les mois et les ann\u00e9es qui viennent\u00a0? Et si nous demandions \u00e0 Dieu par Marie la gr\u00e2ce de dire comme elle\u00a0: \u00ab\u00a0Voici la servante du Seigneur\u00a0: que tout m\u2019advienne selon ta parole.\u00a0\u00bb<\/span><\/p>\n<p style=\"text-align: right;\"><em><span style=\"color: #000000;\">Alexandre-Marie Valder, pr\u00eatre<\/span><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Maternit\u00e9 de Marie, maternit\u00e9 de l&rsquo;\u00c9glise Un jour que J\u00e9sus \u00e9tait en train d&rsquo;enseigner et que sa m\u00e8re et ses fr\u00e8res cherchaient en vain \u00e0 le rejoindre, il dit\u00a0: \u00ab\u00a0Ma m\u00e8re et mes fr\u00e8res sont ceux qui \u00e9coutent la parole de Dieu et la mettent en pratique.\u00a0\u00bb Ainsi est ouverte \u00e0 toute personne la possibilit\u00e9&hellip; <br \/> <a class=\"read-more\" href=\"https:\/\/paroisses-nancy-sud.fr\/HOME\/maternite-de-marie-maternite-de-leglise\/\">Lire la suite<\/a><\/p>\n","protected":false},"author":9,"featured_media":290,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[9],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/posts\/4359"}],"collection":[{"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/comments?post=4359"}],"version-history":[{"count":1,"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/posts\/4359\/revisions"}],"predecessor-version":[{"id":4360,"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/posts\/4359\/revisions\/4360"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/media\/290"}],"wp:attachment":[{"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/media?parent=4359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/categories?post=4359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/tags?post=4359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}