{"id":4414,"date":"2025-01-10T17:55:33","date_gmt":"2025-01-10T16:55:33","guid":{"rendered":"https:\/\/paroisses-nancy-sud.fr\/HOME\/?p=4414"},"modified":"2025-01-10T17:55:33","modified_gmt":"2025-01-10T16:55:33","slug":"lesperance-ne-decoit-pas-2","status":"publish","type":"post","link":"https:\/\/paroisses-nancy-sud.fr\/HOME\/lesperance-ne-decoit-pas-2\/","title":{"rendered":"<strong>L\u2019esp\u00e9rance ne d\u00e9\u00e7oit pas<\/strong>"},"content":{"rendered":"\n<p><span style=\"color: #000000;\"><strong>L\u2019esp\u00e9rance ne d\u00e9\u00e7oit pas<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Le 9 mai 2024, jour de la f\u00eate de l\u2019Ascension, le Pape Fran\u00e7ois a publi\u00e9\u00a0<em>Spes non confundit<\/em>,\u00a0\u00ab l\u2019esp\u00e9rance ne d\u00e9\u00e7oit pas \u00bb, la bulle d\u2019indiction du jubil\u00e9 ordinaire de 2025.\u00a0En voici de beaux extraits.<\/strong><\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>N\u00b08<\/strong> : \u00ab Le premier signe d\u2019esp\u00e9rance doit se traduire par\u00a0<strong>la paix<\/strong>\u00a0pour le monde plong\u00e9,\u00a0une fois encore, dans la trag\u00e9die de la guerre. \u00bb<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>N\u00b09<\/strong> : \u00ab La communaut\u00e9 chr\u00e9tienne doit \u00eatre la premi\u00e8re \u00e0 soutenir\u00a0<strong>une alliance sociale\u00a0<\/strong>pour l\u2019esp\u00e9rance, qui soit inclusive et non id\u00e9ologique, et qui travaille \u00e0 un avenir marqu\u00e9\u00a0par le sourire de nombre d\u2019enfants qui viendront remplir de top nombreux berceaux vides\u00a0en plusieurs lieux dans le monde. Mais chacun en r\u00e9alit\u00e9, a besoin de retrouver\u00a0la joie de vivre car l\u2019\u00eatre humain, cr\u00e9\u00e9 \u00e0 l\u2019image et \u00e0 la ressemblance de Dieu,\u00a0ne peut se contenter de survivre ou de vivoter, de se conformer au pr\u00e9sent\u00a0en se laissant satisfaire de r\u00e9alit\u00e9s uniquement mat\u00e9rielles. \u00bb<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>N\u00b010<\/strong> : \u00ab Au cours de l\u2019ann\u00e9e jubilaire, nous serons appel\u00e9s \u00e0 \u00eatre\u00a0<strong>des signes tangibles d\u2019esp\u00e9rance<\/strong>\u00a0pour de nombreux fr\u00e8res et s\u0153urs qui vivent dans des conditions de d\u00e9tresse. \u00bb<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>N\u00b015<\/strong> : \u00ab Le Jubil\u00e9 nous rappelle que\u00a0<strong>les biens de la Terre\u00a0<\/strong>ne sont pas destin\u00e9s \u00e0 quelques privil\u00e9gi\u00e9s mais \u00e0 tous. \u00bb<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>N\u00b018<\/strong> : \u00ab Oui, nous devons \u201cd\u00e9border d\u2019esp\u00e9rance\u201d (cf. Rm 15, 13) pour\u00a0<strong>t\u00e9moigner\u00a0de mani\u00e8re cr\u00e9dible et attrayante de la foi et de l\u2019amour<\/strong>\u00a0que nous portons dans notre c\u0153ur ; pour que la foi soit joyeuse, la charit\u00e9 enthousiaste ; pour que chacun puisse donner\u00a0ne serait-ce qu\u2019un sourire, un geste d\u2019amiti\u00e9, un regard fraternel, une \u00e9coute sinc\u00e8re,\u00a0un service gratuit, en sachant que, dans l\u2019Esprit de J\u00e9sus, cela peut devenir une semence f\u00e9conde d\u2019esp\u00e9rance pour ceux qui la re\u00e7oivent. Mais quel est le fondement de notre esp\u00e9rance ?\u00a0Pour le comprendre, il est bon de s\u2019arr\u00eater sur les raisons de notre esp\u00e9rance (cf. 1 P 3, 15). \u00bb<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>N\u00b020<\/strong> :\u00a0J\u00e9sus mort et ressuscit\u00e9 est le c\u0153ur de notre foi. [\u2026]\u00a0L\u2019esp\u00e9rance chr\u00e9tienne consiste pr\u00e9cis\u00e9ment en ceci : face \u00e0 la mort, o\u00f9 tout semble finir,\u00a0nous recevons la certitude que, gr\u00e2ce au Christ, par sa gr\u00e2ce qui nous est communiqu\u00e9e dans le Bapt\u00eame,\u00a0<strong>\u00ab la vie n\u2019est pas d\u00e9truite, elle est transform\u00e9e \u00bb<\/strong>\u00a0pour toujours.<\/span><\/p>\n<p style=\"text-align: right;\"><span style=\"color: #000000;\"><em>Morceaux choisis de la Bulle d\u2019indiction, dioc\u00e8se de Nancy<\/em><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019esp\u00e9rance ne d\u00e9\u00e7oit pas Le 9 mai 2024, jour de la f\u00eate de l\u2019Ascension, le Pape Fran\u00e7ois a publi\u00e9\u00a0Spes non confundit,\u00a0\u00ab l\u2019esp\u00e9rance ne d\u00e9\u00e7oit pas \u00bb, la bulle d\u2019indiction du jubil\u00e9 ordinaire de 2025.\u00a0En voici de beaux extraits. N\u00b08 : \u00ab Le premier signe d\u2019esp\u00e9rance doit se traduire par\u00a0la paix\u00a0pour le monde plong\u00e9,\u00a0une fois encore,&hellip; <br \/> <a class=\"read-more\" href=\"https:\/\/paroisses-nancy-sud.fr\/HOME\/lesperance-ne-decoit-pas-2\/\">Lire la suite<\/a><\/p>\n","protected":false},"author":5,"featured_media":523,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/posts\/4414"}],"collection":[{"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/comments?post=4414"}],"version-history":[{"count":1,"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/posts\/4414\/revisions"}],"predecessor-version":[{"id":4415,"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/posts\/4414\/revisions\/4415"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/media\/523"}],"wp:attachment":[{"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/media?parent=4414"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/categories?post=4414"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/tags?post=4414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}