{"id":918,"date":"2021-04-11T17:24:57","date_gmt":"2021-04-11T15:24:57","guid":{"rendered":"https:\/\/paroisses-nancy-sud.fr\/HOME\/?p=918"},"modified":"2021-04-11T17:25:29","modified_gmt":"2021-04-11T15:25:29","slug":"merci-thomas-edito-du-11-avril-2021","status":"publish","type":"post","link":"https:\/\/paroisses-nancy-sud.fr\/HOME\/merci-thomas-edito-du-11-avril-2021\/","title":{"rendered":"Merci Thomas (\u00e9dito du 11 avril 2021)"},"content":{"rendered":"\n<p><span style=\"color: #000000;\">D\u2019abord, Thomas, pourquoi n\u2019\u00e9tais-tu pas avec tes amis, dans cette maison bien verrouill\u00e9e quand \u00ab\u00a0J\u00e9sus vint, et il \u00e9tait l\u00e0 au milieu d\u2019eux\u00a0\u00bb\u00a0? Sans doute, comme nous, avais-tu \u00e0 faire\u2026Pas l\u00e0 au bon moment, au bon endroit\u2026<\/span><\/p>\n<p><span style=\"color: #000000;\">Alors, puisque tu avais manqu\u00e9 ce rendez-vous inattendu, il t\u2019a fallu \u00e9couter le r\u00e9cit de tes amis\u00a0: incroyable, inimaginable cette histoire de r\u00e9surrection\u2026Naturellement, tu ne les as pas crus\u2026Nous aurions fait comme toi\u2026<\/span><\/p>\n<p><span style=\"color: #000000;\">Tu t\u2019es donc ent\u00eat\u00e9\u00a0: \u00ab\u00a0si je ne vois pas\u2026si je ne touche pas\u2026non, je ne croirai pas\u00a0!\u00a0\u00bb.<\/span><\/p>\n<p><span style=\"color: #000000;\">Et le Seigneur a patient\u00e9 huit jours, peut-\u00eatre le temps de bousculer ta t\u00eate et ton c\u0153ur, avant d\u2019\u00eatre \u00e0 nouveau pr\u00e9sent parmi vous. Alors, boulevers\u00e9, tu n\u2019as rien pu dire de plus que cette formidable pri\u00e8re\u00a0: \u00ab\u00a0Mon Seigneur et mon Dieu\u00a0!\u00a0\u00bb. Elle contient en deux mots toute ta foi, ta conversion, ton adoration, l\u2019aveu de ton doute peut-\u00eatre.<\/span><\/p>\n<p><span style=\"color: #000000;\">Merci Thomas pour ton incr\u00e9dulit\u00e9 et ton insistance\u00a0: elles sont \u00e0 notre hauteur d\u2019homme, \u00e0 la mesure de nos doutes, et nous disent beaucoup de la mis\u00e9ricorde et de la patience de Dieu envers nous.<\/span><\/p>\n<p><span style=\"color: #000000;\">Finalement, ce n\u2019est pas parce que nous ne pouvons pas nous repr\u00e9senter la r\u00e9surrection que nous ne pouvons pas la comprendre\u00a0: nous faisons parfois l\u2019exp\u00e9rience d\u2019une rencontre d\u00e9cisive qui nous transforme\u2026<\/span><\/p>\n<p><span style=\"color: #000000;\">Le r\u00e9veil de nos jardins, le chant des oiseaux, le vert des prairies sont signes de r\u00e9surrection. Un coup de fil inattendu, une visite inesp\u00e9r\u00e9e sont signes de r\u00e9surrection. L\u2019aide qu\u2019on offre \u00e0 un voisin, \u00e0 des personnes en difficult\u00e9, la visite \u00e0 un malade sont signes de r\u00e9surrection&#8230;<\/span><\/p>\n<p><span style=\"color: #000000;\">C\u2019est dans ces exp\u00e9riences de nos vies quotidiennes que s\u2019inscrit la rencontre du Ressuscit\u00e9\u00a0!<\/span><\/p>\n<p style=\"text-align: right;\"><span style=\"color: #000000;\">\u00c9quipe de Flavigny + le missel des dimanches<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u2019abord, Thomas, pourquoi n\u2019\u00e9tais-tu pas avec tes amis, dans cette maison bien verrouill\u00e9e quand \u00ab\u00a0J\u00e9sus vint, et il \u00e9tait l\u00e0 au milieu d\u2019eux\u00a0\u00bb\u00a0? Sans doute, comme nous, avais-tu \u00e0 faire\u2026Pas l\u00e0 au bon moment, au bon endroit\u2026 Alors, puisque tu avais manqu\u00e9 ce rendez-vous inattendu, il t\u2019a fallu \u00e9couter le r\u00e9cit de tes amis\u00a0: incroyable,&hellip; <br \/> <a class=\"read-more\" href=\"https:\/\/paroisses-nancy-sud.fr\/HOME\/merci-thomas-edito-du-11-avril-2021\/\">Lire la suite<\/a><\/p>\n","protected":false},"author":2,"featured_media":523,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/posts\/918"}],"collection":[{"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/comments?post=918"}],"version-history":[{"count":2,"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/posts\/918\/revisions"}],"predecessor-version":[{"id":920,"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/posts\/918\/revisions\/920"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/media\/523"}],"wp:attachment":[{"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/media?parent=918"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/categories?post=918"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/paroisses-nancy-sud.fr\/HOME\/wp-json\/wp\/v2\/tags?post=918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}